{"id":2961,"date":"2010-09-07T21:21:50","date_gmt":"2010-09-07T19:21:50","guid":{"rendered":"http:\/\/scaloni.it\/popinga\/?p=2961"},"modified":"2010-09-07T21:21:50","modified_gmt":"2010-09-07T19:21:50","slug":"incrocio-del-ciarnin-qualcosa-se-mosso","status":"publish","type":"post","link":"https:\/\/scaloni.it\/popinga\/incrocio-del-ciarnin-qualcosa-se-mosso\/","title":{"rendered":"Incrocio del Ciarnin: qualcosa s&#8217;\u00e8 mosso"},"content":{"rendered":"<p style=\"text-align: center;\"><a href=\"http:\/\/picasaweb.google.com\/popinga.it\/StradeASenigallia#5510179643417905282\" target=\"_blank\"><img decoding=\"async\" loading=\"lazy\" class=\"size-medium wp-image-2963  alignleft\" title=\"Foto428\" src=\"http:\/\/scaloni.it\/popinga\/wp-content\/uploads\/2010\/09\/Foto428-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/scaloni.it\/popinga\/wp-content\/uploads\/2010\/09\/Foto428-300x225.jpg 300w, https:\/\/scaloni.it\/popinga\/wp-content\/uploads\/2010\/09\/Foto428-1024x768.jpg 1024w, https:\/\/scaloni.it\/popinga\/wp-content\/uploads\/2010\/09\/Foto428.jpg 2048w\" sizes=\"(max-width: 300px) 85vw, 300px\" \/><\/a><a href=\"http:\/\/picasaweb.google.com\/popinga.it\/StradeASenigallia#5510179713081286002\" target=\"_blank\"><img decoding=\"async\" loading=\"lazy\" class=\"size-medium wp-image-2962 aligncenter\" title=\"Foto430\" src=\"http:\/\/scaloni.it\/popinga\/wp-content\/uploads\/2010\/09\/Foto430-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/scaloni.it\/popinga\/wp-content\/uploads\/2010\/09\/Foto430-300x225.jpg 300w, https:\/\/scaloni.it\/popinga\/wp-content\/uploads\/2010\/09\/Foto430-1024x768.jpg 1024w, https:\/\/scaloni.it\/popinga\/wp-content\/uploads\/2010\/09\/Foto430.jpg 2048w\" sizes=\"(max-width: 300px) 85vw, 300px\" \/><\/a><\/p>\n<p>La nostra <a href=\"http:\/\/scaloni.it\/popinga\/ciarnin-quando-il-prossimo-incidente-mortale\/\">denuncia<\/a> sulla pericolosit\u00e0 dell&#8217;incrocio-sottospassaggio del Ciarnin ha sortito qualche effetto.<br \/>\nNei\u00a0giorni dopo Ferragosto l&#8217;ANAS, su sollecito del Comune, ha\u00a0installato dei paletti di plastica muniti di\u00a0catarifrangente, che impediscono il parcheggio lungo la Statale e\u00a0migliorano sensibilmente la visuale.<\/p>\n<p>Un intervento\u00a0tempestivo e tutto sommato\u00a0efficace: complimenti.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La nostra denuncia sulla pericolosit\u00e0 dell&#8217;incrocio-sottospassaggio del Ciarnin ha sortito qualche effetto. Nei\u00a0giorni dopo Ferragosto l&#8217;ANAS, su sollecito del Comune, ha\u00a0installato dei paletti di plastica muniti di\u00a0catarifrangente, che impediscono il parcheggio lungo la Statale e\u00a0migliorano sensibilmente la visuale. Un intervento\u00a0tempestivo e tutto sommato\u00a0efficace: complimenti.<\/p>\n","protected":false},"author":12,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[32,2],"tags":[1384,1383,149,329],"_links":{"self":[{"href":"https:\/\/scaloni.it\/popinga\/wp-json\/wp\/v2\/posts\/2961"}],"collection":[{"href":"https:\/\/scaloni.it\/popinga\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/scaloni.it\/popinga\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/scaloni.it\/popinga\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/scaloni.it\/popinga\/wp-json\/wp\/v2\/comments?post=2961"}],"version-history":[{"count":1,"href":"https:\/\/scaloni.it\/popinga\/wp-json\/wp\/v2\/posts\/2961\/revisions"}],"predecessor-version":[{"id":2965,"href":"https:\/\/scaloni.it\/popinga\/wp-json\/wp\/v2\/posts\/2961\/revisions\/2965"}],"wp:attachment":[{"href":"https:\/\/scaloni.it\/popinga\/wp-json\/wp\/v2\/media?parent=2961"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/scaloni.it\/popinga\/wp-json\/wp\/v2\/categories?post=2961"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/scaloni.it\/popinga\/wp-json\/wp\/v2\/tags?post=2961"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}