{"id":248,"date":"2006-01-27T12:47:35","date_gmt":"2006-01-27T10:47:35","guid":{"rendered":"506663042"},"modified":"2006-12-27T12:07:48","modified_gmt":"2006-12-27T20:07:48","slug":"quando_il_giornalismo_va_a_farsi_benedire_3","status":"publish","type":"post","link":"https:\/\/scaloni.it\/popinga\/quando_il_giornalismo_va_a_farsi_benedire_3\/","title":{"rendered":"Quando il giornalismo va a farsi benedire \/3"},"content":{"rendered":"<p>Chiss\u00e0 a cosa si riferiva don Gesualdo Purziani quando, in occasione dell\u2019incontro del Vescovo coi giornalisti per il loro patrono San Francesco di Sales, ha parlato di <em>\u00abimpegno etico\u00bb<\/em>. Non \u00e8 neppure chiaro cosa intendesse per <em>\u00abvalori di riferimento\u00bb<\/em> de <em>La Voce Misena<\/em>, settimanale di cui \u00e8 direttore editoriale.<br \/>\nSpero che l\u2019etica giornalistica e i valori di riferimento non siano quelli che il sottoscritto ha intravisto qualche mese fa: <em>La Voce Misena<\/em> ha pubblicato un <a title=\"Padre Alberto Teloni: Blasfemia\" href=\"http:\/\/www.vocemisena.it\/2005\/25\/vm25.pdf\" target=\"_blank\">corsivo<\/a>, ha censurato la <a title=\"Popinga: Blasfemo chi?\" href=\"http:\/\/scaloni.it\/popinga\/blasfemo_chi\" target=\"_self\">replica<\/a> di un lettore (io) a quel corsivo e infine ha pubblicato la <a title=\"Padre Alberto Teloni: Rispondo\" href=\"http:\/\/www.vocemisena.it\/2005\/29\/vm29.pdf\" target=\"_blank\">contro-replica<\/a> del corsivista.<br \/>\nPer questo genere di \u201cimpegno etico\u201d, in qualunque giornale, il giornalista e il direttore si vergognerebbero e chiederebbero scusa. Nei Paesi a cultura anglosassone, poi, questo \u201cimpegno etico\u201d verrebbe premiato con una bella cacciata a pedate dalla redazione.<br \/>\nDalle parti di Via Cavallotti,\u00a0invece,\u00a0fanno pure gli offesi&#8230;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Chiss\u00e0 a cosa si riferiva don Gesualdo Purziani quando, in occasione dell\u2019incontro del Vescovo coi giornalisti per il loro patrono San Francesco di Sales, ha parlato di \u00abimpegno etico\u00bb. Non \u00e8 neppure chiaro cosa intendesse per \u00abvalori di riferimento\u00bb de La Voce Misena, settimanale di cui \u00e8 direttore editoriale. Spero che l\u2019etica giornalistica e i &hellip; <a href=\"https:\/\/scaloni.it\/popinga\/quando_il_giornalismo_va_a_farsi_benedire_3\/\" class=\"more-link\">Leggi tutto<span class=\"screen-reader-text\"> &#8220;Quando il giornalismo va a farsi benedire \/3&#8221;<\/span><\/a><\/p>\n","protected":false},"author":12,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[393,12,114],"_links":{"self":[{"href":"https:\/\/scaloni.it\/popinga\/wp-json\/wp\/v2\/posts\/248"}],"collection":[{"href":"https:\/\/scaloni.it\/popinga\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/scaloni.it\/popinga\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/scaloni.it\/popinga\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/scaloni.it\/popinga\/wp-json\/wp\/v2\/comments?post=248"}],"version-history":[{"count":0,"href":"https:\/\/scaloni.it\/popinga\/wp-json\/wp\/v2\/posts\/248\/revisions"}],"wp:attachment":[{"href":"https:\/\/scaloni.it\/popinga\/wp-json\/wp\/v2\/media?parent=248"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/scaloni.it\/popinga\/wp-json\/wp\/v2\/categories?post=248"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/scaloni.it\/popinga\/wp-json\/wp\/v2\/tags?post=248"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}