{"id":2,"count":180,"description":"Cronache e storie da Senigallia","link":"https:\/\/scaloni.it\/popinga\/canali\/Senigallia\/","name":"Senigallia","slug":"Senigallia","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/scaloni.it\/popinga\/wp-json\/wp\/v2\/categories\/2"}],"collection":[{"href":"https:\/\/scaloni.it\/popinga\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/scaloni.it\/popinga\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/scaloni.it\/popinga\/wp-json\/wp\/v2\/posts?categories=2"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}